{"id":12784,"date":"2019-06-27T20:37:28","date_gmt":"2019-06-27T19:37:28","guid":{"rendered":"http:\/\/www.wjst.de\/blog\/?p=12784"},"modified":"2019-06-28T06:02:47","modified_gmt":"2019-06-28T05:02:47","slug":"den-fuss-vom-gas","status":"publish","type":"post","link":"https:\/\/www.wjst.de\/blog\/sciencesurf\/2019\/06\/den-fuss-vom-gas\/","title":{"rendered":"Den Fuss vom Gas"},"content":{"rendered":"<p>Ein lesenswertes Interview in der <a href=\"https:\/\/www.zeit.de\/zeit-magazin\/leben\/2019-06\/frank-trentmann-konsum-glueck-interview\">ZEIT<\/a> mit Frank Trentmann &#8220;<a href=\"https:\/\/www.randomhouse.de\/Paperback\/Herrschaft-der-Dinge\/Frank-Trentmann\/Pantheon\/e530044.rhd\">Die Herrschaft der Dinge<\/a>&#8220;. K\u00f6nnen wir mit Optimierungen im Alltag zu einem guten Leben gelangen?\u00a0 Der Historiker Frank Trentmann sagt: Wir sollten endlich aufh\u00f6ren, unserem Ich hinterherzujagen.<\/p>\n<blockquote><p>Die Pension\u00e4re, Manager, Million\u00e4re hingegen hatten Mu\u00dfe. Zeit zu haben war Teil des gehobenen sozialen Status. Wer einen hohen sozialen Status hatte, gab damit an, dass er im Sommer f\u00fcr acht Wochen in seine Villa nach Baden-Baden oder an die C\u00f4te d&#8217;Azur fuhr. Heute ist es genau andersherum: Einen hohen Status haben jene Menschen, die st\u00e4ndig unterwegs und besch\u00e4ftigt sind.<\/p><\/blockquote>\n<p>Und die Optimierung des Alltags in der Wissenschaft?\u00a0Fr\u00fcher war es das Privileg von Wissenschaft, Zeit zu haben, zu lesen, nachzudenken, Schl\u00fcsse zu ziehen, Ideen zu skizzieren. Heute gibt es das nicht mehr, nur noch Emails, Benchmarks, Impact, Fly-in und Fly-out, Meetings, Skype, Hype und PR <a href=\"https:\/\/www.wjst.de\/blog\/sciencesurf\/2019\/06\/asthma-genetics-bigger-is-not-better\/\">q.e.d.<\/a><\/p>\n\n<p>&nbsp;<\/p>\n<div class=\"bottom-note\">\n  <span class=\"mod1\">CC-BY-NC Science Surf , accessed 15.07.2026<\/span>\n <\/div>","protected":false},"excerpt":{"rendered":"<p>Ein lesenswertes Interview in der ZEIT mit Frank Trentmann &#8220;Die Herrschaft der Dinge&#8220;. K\u00f6nnen wir mit Optimierungen im Alltag zu einem guten Leben gelangen?\u00a0 Der Historiker Frank Trentmann sagt: Wir sollten endlich aufh\u00f6ren, unserem Ich hinterherzujagen. Die Pension\u00e4re, Manager, Million\u00e4re hingegen hatten Mu\u00dfe. Zeit zu haben war Teil des gehobenen sozialen Status. Wer einen hohen &hellip; <a href=\"https:\/\/www.wjst.de\/blog\/sciencesurf\/2019\/06\/den-fuss-vom-gas\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Den Fuss vom Gas<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-12784","post","type-post","status-publish","format-standard","hentry","category-philosophy-of-science"],"_links":{"self":[{"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/posts\/12784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/comments?post=12784"}],"version-history":[{"count":6,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/posts\/12784\/revisions"}],"predecessor-version":[{"id":12798,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/posts\/12784\/revisions\/12798"}],"wp:attachment":[{"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/media?parent=12784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/categories?post=12784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/tags?post=12784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}