{"id":12927,"date":"2019-07-07T05:40:07","date_gmt":"2019-07-07T05:40:07","guid":{"rendered":"http:\/\/www.wjst.de\/blog\/?p=12927"},"modified":"2019-07-30T16:52:24","modified_gmt":"2019-07-30T16:52:24","slug":"wer-einmal-lugt-dem-glaubt-man-nicht","status":"publish","type":"post","link":"https:\/\/www.wjst.de\/blog\/sciencesurf\/2019\/07\/wer-einmal-lugt-dem-glaubt-man-nicht\/","title":{"rendered":"Wer einmal l\u00fcgt, dem glaubt man nicht"},"content":{"rendered":"<p>Es ist eines der gro\u00dfen Probleme der Klimaforschung, dass man sie \u00a0zu lange nicht ernst genommen hat &#8211; unter anderem wegen der \u00a0vielen Experten f\u00fcr das Waldsterben. \u00a0<a href=\"https:\/\/de.wikipedia.org\/wiki\/Waldsterben\">Wikipedia Timeline<\/a>.<\/p>\n<blockquote><p><strong>1979<\/strong><br \/>\nwarnten die Forstwissenschaftler Bernhard Ulrich und Peter Sch\u00fctt vor einem bevorstehenden bzw. stattfindenden Waldsterben und forderten eine Verbesserung der Luftreinhaltung&#8230;.<br \/>\n<strong>1984<\/strong><br \/>\nsetzte eine Normalisierung des Umgangs der Forstwissenschaftler mit dem Waldsterben ein, das zunehmend weniger politisch und emotional besetzt war.<br \/>\n<strong>1992<\/strong><br \/>\nin der dritten Phase differenzierte sich die reine Waldschadensforschung in eine breiter angelegte Wald\u00f6kosystemforschung. &#8230;<br \/>\n<strong>2003<\/strong><br \/>\nerkl\u00e4rte die damalige Bundeslandwirtschaftsministerin Renate K\u00fcnast in \u00dcbereinstimmung mit Befunden der europ\u00e4ischen Nachbarn das \u201eWaldsterben\u201c f\u00fcr beendet.<\/p><\/blockquote>\n\n<p>&nbsp;<\/p>\n<div class=\"bottom-note\">\n  <span class=\"mod1\">CC-BY-NC Science Surf , accessed 02.09.2026<\/span>\n <\/div>","protected":false},"excerpt":{"rendered":"<p>Es ist eines der gro\u00dfen Probleme der Klimaforschung, dass man sie \u00a0zu lange nicht ernst genommen hat &#8211; unter anderem wegen der \u00a0vielen Experten f\u00fcr das Waldsterben. \u00a0Wikipedia Timeline. 1979 warnten die Forstwissenschaftler Bernhard Ulrich und Peter Sch\u00fctt vor einem bevorstehenden bzw. stattfindenden Waldsterben und forderten eine Verbesserung der Luftreinhaltung&#8230;. 1984 setzte eine Normalisierung des &hellip; <a href=\"https:\/\/www.wjst.de\/blog\/sciencesurf\/2019\/07\/wer-einmal-lugt-dem-glaubt-man-nicht\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Wer einmal l\u00fcgt, dem glaubt man nicht<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-12927","post","type-post","status-publish","format-standard","hentry","category-note-worthy"],"_links":{"self":[{"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/posts\/12927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/comments?post=12927"}],"version-history":[{"count":3,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/posts\/12927\/revisions"}],"predecessor-version":[{"id":12931,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/posts\/12927\/revisions\/12931"}],"wp:attachment":[{"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/media?parent=12927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/categories?post=12927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/tags?post=12927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}