{"id":15769,"date":"2020-03-25T17:11:35","date_gmt":"2020-03-25T17:11:35","guid":{"rendered":"http:\/\/www.wjst.de\/blog\/?p=15769"},"modified":"2020-05-03T07:09:53","modified_gmt":"2020-05-03T07:09:53","slug":"task-force-epidemiologie-covid-19","status":"publish","type":"post","link":"https:\/\/www.wjst.de\/blog\/sciencesurf\/2020\/03\/task-force-epidemiologie-covid-19\/","title":{"rendered":"Task Force Epidemiologie COVID-19"},"content":{"rendered":"<p>Wir brauchen eine professionelle Priorisierung, Koordinierung und Kommunikation der Forschung zu Nicht-Pharmakologischen Interventionen (NPI).\u00a0 <a href=\"https:\/\/www.bihealth.org\/de\/aktuell\/aufruf-nationale-taskforce-covid-19-evidenz\/\">Ich unterst\u00fctze damit den Aufruf des QUEST Center (Quality, Ethics, Open Science, Translation), Berlin Institute of Health (BIH)<\/a>.<\/p>\n<p>In der laufenden Pandemiesituation fehlen uns nach den weitreichenden und erstmal notwendigen Beschr\u00e4nkungen bev\u00f6lkerungsbezogene Daten, die gebraucht werden, um die laufenden Massnahmen zu evaluieren und zu steuern. Die bisher einzigen populationsbasierten Daten in Deutschland finden sich in den <a href=\"https:\/\/influenza.rki.de\/Wochenberichte.aspx\">Influenza Wochenberichten des RKI<\/a> bei den in der 12. KW in 3 von 193 untersuchten Sentinelproben (1,6 %) SARS-CoV-2 identifiziert wurde.<\/p>\n<p>Mein Vorschlag ist eine \u00c4rzte Surveillance Studie, die Vorschl\u00e4ge von <a href=\"http:\/\/dx.doi.org\/10.1056\/nejmp2002125\">Lipsitch<\/a> aufgreift und auf dem\u00a0 Konzept von <a href=\"http:\/\/dx.doi.org\/10.3399\/bjgp08x319486\">Cowling<\/a> aufsetzt. Daf\u00fcr wird randomisiert eine nach Alter, Region und Geschlecht geschichtete Stichprobe von \u00c4rzte:innen Haushalten gezogen. Eine solche Basiserhebung wird im \u00fcbrigen auch von Cochrane\/EBM und anderen Epidemiologen gefordert [<a href=\"https:\/\/www.wjst.de\/blog\/sciencesurf\/2020\/03\/inkubationszeit-des-coronavirus\/12\/\">1<\/a>, <a href=\"https:\/\/www.spiegel.de\/wissenschaft\/medizin\/coronavirus-die-zahlen-sind-vollkommen-unzuverlaessig-a-7535b78f-ad68-4fa9-9533-06a224cc9250\">2<\/a>, <a href=\"https:\/\/www.dgepi.de\/de\/aktuelles\/article\/aktualisierte-stellungnahme-der-deutschen-gesellschaft-fuer-epidemiologie-dgepi-zur-verbreitung-des-neuen-coronavirus-sars-cov-2\/109\">3<\/a>].<\/p>\n<p>\u00c4rzten\/\u00c4rztinnen kommt in der Pandemie-Situation eine besondere Bedeutung zu; sie eignen aber auch selbst als Untersuchungsgegenstand, da es unter den aktuellen Bedingungen gro\u00dfe logistische Probleme f\u00fcr eine klassische epidemiologische Studie gibt. Nach dem Prinzip der bekannten Physicians\u2019 Health oder British Doctor Studies k\u00f6nnen in wenigen Tagen verl\u00e4ssliche Basiszahlen generiert werden k\u00f6nnen, ohne dass hier zus\u00e4tzlich die Infektion durch Untersuchungsteams verbreitet wird.<\/p>\n<p>Die Landes\u00e4rztekammer w\u00fcrde daf\u00fcr eine Zufallsstichprobe von ca 3.000 \u00c4rzten\/\u00c4rztinnen in den Landkreisen ziehen und sie in einem Anschreiben bitten, dass sie kurzfristig bei sich selbst und allen in ihrem Haushalt lebenden Personen Abstriche nehmen bzw die Serologie bestimmen. Erg\u00e4nzt werden kann die Ziehung aus den \u00c4rztehaushalten durch zuf\u00e4llig gezogene Probanden aus der jeweiligen Patientenkartei oder in der N\u00e4he liegenden Adressen aus dem Einwohnermeldeamtsregister. Alle Ergebnisse werden umgehend in eine online Datenbank eingetragen, bei Positivbefund das Tracing an die zust\u00e4ndigen Gesundheits\u00e4mter \u00fcbertragen.<\/p>\n<p>Die Bereitschaft von \u00c4rzten\/\u00c4rztinnen f\u00fcr ein solches Projekt d\u00fcrfte hoch sein, zumal die Teilnehmer den Vorteil haben, ihren Teststatus zu erfahren. F\u00fcr die epidemiologische Forschung werden die Daten anonymisiert.<\/p>\n<p>Ein solches Survey kann in beliebigen Zeitintervallen wiederholt werden, um die zunehmende Durchseuchung beziehungsweise aufkommende Immunit\u00e4t zu messen. Zu kl\u00e4ren bleiben juristische und ethische Fragen, Datenschutz sowie Finanzierung des Projektes.<\/p>\n\n<p>&nbsp;<\/p>\n<div class=\"bottom-note\">\n  <span class=\"mod1\">CC-BY-NC Science Surf , accessed 15.07.2026<\/span>\n <\/div>","protected":false},"excerpt":{"rendered":"<p>Wir brauchen eine professionelle Priorisierung, Koordinierung und Kommunikation der Forschung zu Nicht-Pharmakologischen Interventionen (NPI).\u00a0 Ich unterst\u00fctze damit den Aufruf des QUEST Center (Quality, Ethics, Open Science, Translation), Berlin Institute of Health (BIH). In der laufenden Pandemiesituation fehlen uns nach den weitreichenden und erstmal notwendigen Beschr\u00e4nkungen bev\u00f6lkerungsbezogene Daten, die gebraucht werden, um die laufenden Massnahmen zu &hellip; <a href=\"https:\/\/www.wjst.de\/blog\/sciencesurf\/2020\/03\/task-force-epidemiologie-covid-19\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Task Force Epidemiologie COVID-19<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[3391],"class_list":["post-15769","post","type-post","status-publish","format-standard","hentry","category-note-worthy","tag-covid-19"],"_links":{"self":[{"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/posts\/15769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/comments?post=15769"}],"version-history":[{"count":19,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/posts\/15769\/revisions"}],"predecessor-version":[{"id":15933,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/posts\/15769\/revisions\/15933"}],"wp:attachment":[{"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/media?parent=15769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/categories?post=15769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/tags?post=15769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}