{"id":22579,"date":"2023-08-28T09:45:18","date_gmt":"2023-08-28T07:45:18","guid":{"rendered":"https:\/\/www.wjst.de\/blog\/?p=22579"},"modified":"2023-08-28T09:45:18","modified_gmt":"2023-08-28T07:45:18","slug":"martha-study","status":"publish","type":"post","link":"https:\/\/www.wjst.de\/blog\/sciencesurf\/2023\/08\/martha-study\/","title":{"rendered":"Martha Study"},"content":{"rendered":"<div class=\"acpwd-container\" id=\"acpwd-22579\">\n<p class=\"acpwd-info-message\">This content has restricted access, please email me for the password.<\/p>\n<form class=\"acpwd-form\" action=\"\/blog\/wp-json\/wp\/v2\/posts\/22579#acpwd-22579\" method=\"post\">\n\t<input class=\"acpwd-pass\" type=\"password\" name=\"acpwd-pass\" placeholder=\"\"><input class=\"acpwd-submit\" type=\"submit\" value=\"Get access\"><br \/>\n<\/form>\n<\/div>\n\n<p>&nbsp;<\/p>\n<div class=\"bottom-note\">\n  <span class=\"mod1\">CC-BY-NC Science Surf , accessed 13.05.2026<\/span>\n <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"acpwd-container\" id=\"acpwd-22579\">\n<p class=\"acpwd-info-message\">This content has restricted access, please email me for the password.<\/p>\n<form class=\"acpwd-form\" action=\"\/blog\/wp-json\/wp\/v2\/posts\/22579#acpwd-22579\" method=\"post\">\n\t<input class=\"acpwd-pass\" type=\"password\" name=\"acpwd-pass\" placeholder=\"\"><input class=\"acpwd-submit\" type=\"submit\" value=\"Get access\"><br \/>\n<\/form>\n<\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,3835],"tags":[3676,3163],"class_list":["post-22579","post","type-post","status-publish","format-standard","hentry","category-asthma-allergy","category-password","tag-lmu","tag-von-mutius"],"_links":{"self":[{"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/posts\/22579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/comments?post=22579"}],"version-history":[{"count":2,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/posts\/22579\/revisions"}],"predecessor-version":[{"id":22583,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/posts\/22579\/revisions\/22583"}],"wp:attachment":[{"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/media?parent=22579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/categories?post=22579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wjst.de\/blog\/wp-json\/wp\/v2\/tags?post=22579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}